{"id":44105,"date":"2021-11-25T15:01:50","date_gmt":"2021-11-25T15:01:50","guid":{"rendered":"https:\/\/excellencefrompiedmont.com\/?p=44105"},"modified":"2021-11-25T15:40:57","modified_gmt":"2021-11-25T15:40:57","slug":"il-ritorno-delle-friulane-o-slipperine","status":"publish","type":"post","link":"https:\/\/expi.biz\/en\/il-ritorno-delle-friulane-o-slipperine\/","title":{"rendered":"Il ritorno delle friulane o\u00a0slipperine"},"content":{"rendered":"\n<p><strong><em><br><\/em><\/strong>A met\u00e0 tra delle pantofole e delle ballerine, le <em>friulane<\/em> o <em>furlane<\/em>, sono calzature originarie delle campagne del Friuli dell\u2019800. Venivano cucite a mano dalle donne utilizzando prevalentemente materiali poveri di scarto. Dopo la Prima guerra mondiale le friulane arrivano a Venezia e diventano la scarpa comoda e leggera per i gondolieri, con la scuola di antiscivolo. In seguito, diventarono una pantofola chic di velluto lucido da portare in casa per accogliere gli ospiti, tenendo il piede caldo d\u2019inverno e fresco d\u2019estate. Negli ultimi gli anni, grazie alla loro versatilit\u00e0 e ampiezza di colori, le friulane sono tornate per le strade, diventando un\u2019icona di uno stile elegante e rilassato.<br>Biorn le reinterpreta seguendo i colori delle stagioni e rafforzando la suola in gomma per poterle portare ogni giorno anche fuori casa: le <em><strong>slipperine<\/strong><\/em> in velluto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/excellencefrompiedmont.com\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"721\" data-attachment-id=\"44141\" data-permalink=\"https:\/\/expi.biz\/en\/il-ritorno-delle-friulane-o-slipperine\/schermata-2021-11-25-alle-16-28-18\/\" data-orig-file=\"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?fit=2220%2C1564&amp;ssl=1\" data-orig-size=\"2220,1564\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Schermata-2021-11-25-alle-16.28.18\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?fit=1024%2C721&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/excellencefrompiedmont.com\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18-1024x721.png?resize=1024%2C721&#038;ssl=1\" alt=\"\" class=\"wp-image-44141\" srcset=\"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?resize=1024%2C721&amp;ssl=1 1024w, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?resize=300%2C211&amp;ssl=1 300w, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?resize=768%2C541&amp;ssl=1 768w, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?resize=1536%2C1082&amp;ssl=1 1536w, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?resize=2048%2C1443&amp;ssl=1 2048w, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?resize=700%2C493&amp;ssl=1 700w, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.18.png?w=2120&amp;ssl=1 2120w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><br>Dopo un\u2019estate di colori pastello, sono tornate in atelier con le nuances autunnali: grigio pietra, verde bosco, blu notte e rosso merlot. La novit\u00e0 di questa nuova collezione invernale \u00e8 il modello in velluto nero reinterpretato con la punta in stile ballerina elegante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/excellencefrompiedmont.com\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.01.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"721\" data-attachment-id=\"44143\" data-permalink=\"https:\/\/expi.biz\/en\/il-ritorno-delle-friulane-o-slipperine\/schermata-2021-11-25-alle-16-28-01\/\" data-orig-file=\"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.01-e1638446070405.png?fit=1000%2C705&amp;ssl=1\" data-orig-size=\"1000,705\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Schermata-2021-11-25-alle-16.28.01\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Slipperine black a punta&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.01-e1638446070405.png?fit=1024%2C721&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/excellencefrompiedmont.com\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.28.01-1024x721.png?resize=1024%2C721&#038;ssl=1\" alt=\"\" class=\"wp-image-44143\"\/><\/a><\/figure>\n\n\n\n<p><br>Un classico della tradizione che ritorna e si abbina perfettamente con tutto, in casa e fuori casa, di giorno e di sera.<\/p>\n\n\n\n<p><\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"https:\/\/www.hupso.com\/share\/\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/static.hupso.com\/share\/buttons\/share-small.png?w=1060&#038;ssl=1\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"facebook_send\",\"google\",\"pinterest\",\"email\",\"print\",\"linkedin\");var hupso_counters_lang = \"it_IT\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"LucaMurta\";var hupso_url_c=\"\";var hupso_title_c=\"Il%20ritorno%20delle%20friulane%20o%C2%A0slipperine\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>A met\u00e0 tra delle pantofole e delle ballerine, le friulane o furlane, sono calzature originarie delle campagne del Friuli dell\u2019800&#8230;.<\/p>\n","protected":false},"author":3,"featured_media":44140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[173,174,88,175,176,177],"class_list":["post-44105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-aw21","tag-biornshoes","tag-expi","tag-friulane","tag-slipperine","tag-velluto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il ritorno delle friulane o\u00a0slipperine - Marconi Due<\/title>\n<meta name=\"description\" content=\"Scopri la collezione di Slipperine in velluto di Biorn shoes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il ritorno delle friulane o\u00a0slipperine - Marconi Due\" \/>\n<meta property=\"og:description\" content=\"Scopri la collezione di Slipperine in velluto di Biorn shoes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/\" \/>\n<meta property=\"og:site_name\" content=\"Marconi Due\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-25T15:01:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-25T15:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.22.22-1024x726.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Virginia Porceddu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Virginia Porceddu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/\"},\"author\":{\"name\":\"Virginia Porceddu\",\"@id\":\"https:\\\/\\\/expi.biz\\\/#\\\/schema\\\/person\\\/937f9d3709c81d701c893ba333bb163c\"},\"headline\":\"Il ritorno delle friulane o\u00a0slipperine\",\"datePublished\":\"2021-11-25T15:01:50+00:00\",\"dateModified\":\"2021-11-25T15:40:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/\"},\"wordCount\":209,\"image\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/expi.biz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1\",\"keywords\":[\"AW21\",\"biornshoes\",\"ExPi\",\"friulane\",\"slipperine\",\"velluto\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/\",\"url\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/\",\"name\":\"Il ritorno delle friulane o\u00a0slipperine - Marconi Due\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/expi.biz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1\",\"datePublished\":\"2021-11-25T15:01:50+00:00\",\"dateModified\":\"2021-11-25T15:40:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/#\\\/schema\\\/person\\\/937f9d3709c81d701c893ba333bb163c\"},\"description\":\"Scopri la collezione di Slipperine in velluto di Biorn shoes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/expi.biz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/expi.biz\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1\",\"width\":2212,\"height\":1568},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expi.biz\\\/il-ritorno-delle-friulane-o-slipperine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expi.biz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il ritorno delle friulane o\u00a0slipperine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expi.biz\\\/#website\",\"url\":\"https:\\\/\\\/expi.biz\\\/\",\"name\":\"Marconi Due\",\"description\":\"Qui trovi Biella\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expi.biz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expi.biz\\\/#\\\/schema\\\/person\\\/937f9d3709c81d701c893ba333bb163c\",\"name\":\"Virginia Porceddu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cfe1d44a59573190dc55a41f1fd71642152edaa5c257c2fa87ba38e5a5b4a7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cfe1d44a59573190dc55a41f1fd71642152edaa5c257c2fa87ba38e5a5b4a7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cfe1d44a59573190dc55a41f1fd71642152edaa5c257c2fa87ba38e5a5b4a7c?s=96&d=mm&r=g\",\"caption\":\"Virginia Porceddu\"},\"url\":\"https:\\\/\\\/expi.biz\\\/en\\\/author\\\/virginia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il ritorno delle friulane o\u00a0slipperine - Marconi Due","description":"Scopri la collezione di Slipperine in velluto di Biorn shoes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/","og_locale":"en_US","og_type":"article","og_title":"Il ritorno delle friulane o\u00a0slipperine - Marconi Due","og_description":"Scopri la collezione di Slipperine in velluto di Biorn shoes.","og_url":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/","og_site_name":"Marconi Due","article_published_time":"2021-11-25T15:01:50+00:00","article_modified_time":"2021-11-25T15:40:57+00:00","og_image":[{"width":1024,"height":726,"url":"https:\/\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.22.22-1024x726.png","type":"image\/png"}],"author":"Virginia Porceddu","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Virginia Porceddu","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/#article","isPartOf":{"@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/"},"author":{"name":"Virginia Porceddu","@id":"https:\/\/expi.biz\/#\/schema\/person\/937f9d3709c81d701c893ba333bb163c"},"headline":"Il ritorno delle friulane o\u00a0slipperine","datePublished":"2021-11-25T15:01:50+00:00","dateModified":"2021-11-25T15:40:57+00:00","mainEntityOfPage":{"@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/"},"wordCount":209,"image":{"@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1","keywords":["AW21","biornshoes","ExPi","friulane","slipperine","velluto"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/","url":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/","name":"Il ritorno delle friulane o\u00a0slipperine - Marconi Due","isPartOf":{"@id":"https:\/\/expi.biz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/#primaryimage"},"image":{"@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1","datePublished":"2021-11-25T15:01:50+00:00","dateModified":"2021-11-25T15:40:57+00:00","author":{"@id":"https:\/\/expi.biz\/#\/schema\/person\/937f9d3709c81d701c893ba333bb163c"},"description":"Scopri la collezione di Slipperine in velluto di Biorn shoes.","breadcrumb":{"@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/#primaryimage","url":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1","contentUrl":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1","width":2212,"height":1568},{"@type":"BreadcrumbList","@id":"https:\/\/expi.biz\/il-ritorno-delle-friulane-o-slipperine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expi.biz\/"},{"@type":"ListItem","position":2,"name":"Il ritorno delle friulane o\u00a0slipperine"}]},{"@type":"WebSite","@id":"https:\/\/expi.biz\/#website","url":"https:\/\/expi.biz\/","name":"Marconi Due","description":"Qui trovi Biella","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expi.biz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/expi.biz\/#\/schema\/person\/937f9d3709c81d701c893ba333bb163c","name":"Virginia Porceddu","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6cfe1d44a59573190dc55a41f1fd71642152edaa5c257c2fa87ba38e5a5b4a7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6cfe1d44a59573190dc55a41f1fd71642152edaa5c257c2fa87ba38e5a5b4a7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cfe1d44a59573190dc55a41f1fd71642152edaa5c257c2fa87ba38e5a5b4a7c?s=96&d=mm&r=g","caption":"Virginia Porceddu"},"url":"https:\/\/expi.biz\/en\/author\/virginia\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-25-alle-16.22.22.png?fit=2212%2C1568&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6MAXr-btn","jetpack-related-posts":[{"id":44087,"url":"https:\/\/expi.biz\/en\/44087-2\/","url_meta":{"origin":44105,"position":0},"title":"Alpaca Hug &#8211; collezione in edizione limitata","author":"Virginia Porceddu","date":"Tuesday November 23rd, 2021","format":false,"excerpt":"Cappellificio Biellese 1935 apre la stagione Autunno-Inverno 2021 con una capsule collection in edizione limitata realizzata con soffice tessuto in Baby Alpaca. Undici modelli, tra uomo, donna e unisex, declinati con pattern e colori naturali: classici check, larghi e stretti in verdone, melange grigio e blu, boucl\u00e9 bianco e nero,\u2026","rel":"","context":"In \"alpacahug\"","block_context":{"text":"alpacahug","link":"https:\/\/expi.biz\/en\/tag\/alpacahug\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-23-alle-22.06.35.png?fit=1200%2C847&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-23-alle-22.06.35.png?fit=1200%2C847&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-23-alle-22.06.35.png?fit=1200%2C847&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-23-alle-22.06.35.png?fit=1200%2C847&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2021\/11\/Schermata-2021-11-23-alle-22.06.35.png?fit=1200%2C847&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44464,"url":"https:\/\/expi.biz\/en\/qualche-idea-per-san-valentino\/","url_meta":{"origin":44105,"position":1},"title":"Qualche idea per San Valentino","author":"Virginia Porceddu","date":"Thursday February 10th, 2022","format":false,"excerpt":"Febbraio \u00e8 il mese del comfort e delle coccole aspettando l'arrivo della Primavera.Se ci mettiamo San Valentino di mezzo, ecco che i motivi per farsi un regalo iniziano ad essere tanti! Abbiamo selezionato per voi alcune idee per quest'occasione, che sia un regalo per voi stessi o un pensiero speciale\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2022\/02\/Selezione-di.png?fit=1200%2C848&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2022\/02\/Selezione-di.png?fit=1200%2C848&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2022\/02\/Selezione-di.png?fit=1200%2C848&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2022\/02\/Selezione-di.png?fit=1200%2C848&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2022\/02\/Selezione-di.png?fit=1200%2C848&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42705,"url":"https:\/\/expi.biz\/en\/bielmonte-capsule-collection\/","url_meta":{"origin":44105,"position":2},"title":"(Italiano) Bielmonte capsule collection","author":"Murta G. Cardoso","date":"Friday October 23rd, 2020","format":false,"excerpt":"Sorry, this entry is only available in Italiano.","rel":"","context":"In &quot;ExPi&quot;","block_context":{"text":"ExPi","link":"https:\/\/expi.biz\/en\/category\/expi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/IMG_9943-e1603445065635.jpg?fit=1000%2C510&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/IMG_9943-e1603445065635.jpg?fit=1000%2C510&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/IMG_9943-e1603445065635.jpg?fit=1000%2C510&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/IMG_9943-e1603445065635.jpg?fit=1000%2C510&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42683,"url":"https:\/\/expi.biz\/en\/genomicart\/","url_meta":{"origin":44105,"position":3},"title":"(Italiano) GenomicArt","author":"Murta G. Cardoso","date":"Monday October 12th, 2020","format":false,"excerpt":"Sorry, this entry is only available in Italiano.","rel":"","context":"In &quot;ExPi&quot;","block_context":{"text":"ExPi","link":"https:\/\/expi.biz\/en\/category\/expi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/1601370907001-IMG-20200927-WA0000.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/1601370907001-IMG-20200927-WA0000.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/1601370907001-IMG-20200927-WA0000.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/1601370907001-IMG-20200927-WA0000.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2020\/10\/1601370907001-IMG-20200927-WA0000.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41736,"url":"https:\/\/expi.biz\/en\/famiglia-mantico-si-allarga\/","url_meta":{"origin":44105,"position":4},"title":"(Italiano) La famiglia MANTICO si allarga","author":"Murta G. Cardoso","date":"Thursday October 26th, 2017","format":false,"excerpt":"Sorry, this entry is only available in Italiano.","rel":"","context":"In &quot;ExPi Company&quot;","block_context":{"text":"ExPi Company","link":"https:\/\/expi.biz\/en\/category\/expicompany\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2017\/10\/IMG_1294-2.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2017\/10\/IMG_1294-2.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2017\/10\/IMG_1294-2.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2017\/10\/IMG_1294-2.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2017\/10\/IMG_1294-2.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42162,"url":"https:\/\/expi.biz\/en\/idee-natalizie-made-in-expi\/","url_meta":{"origin":44105,"position":5},"title":"(Italiano) Idee natalizie Made in ExPi","author":"Murta G. Cardoso","date":"Thursday November 29th, 2018","format":false,"excerpt":"Sorry, this entry is only available in Italiano.","rel":"","context":"In &quot;ExPi&quot;","block_context":{"text":"ExPi","link":"https:\/\/expi.biz\/en\/category\/expi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2018\/11\/adult-background-beard-716658-e1542812333984.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2018\/11\/adult-background-beard-716658-e1542812333984.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2018\/11\/adult-background-beard-716658-e1542812333984.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2018\/11\/adult-background-beard-716658-e1542812333984.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/expi.biz\/wp-content\/uploads\/2018\/11\/adult-background-beard-716658-e1542812333984.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/posts\/44105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/comments?post=44105"}],"version-history":[{"count":1,"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/posts\/44105\/revisions"}],"predecessor-version":[{"id":44144,"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/posts\/44105\/revisions\/44144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/media\/44140"}],"wp:attachment":[{"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/media?parent=44105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/categories?post=44105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expi.biz\/en\/wp-json\/wp\/v2\/tags?post=44105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}